{"id":48,"date":"2023-07-30T09:38:29","date_gmt":"2023-07-30T09:38:29","guid":{"rendered":"https:\/\/www.tracosepontos.pt\/blog\/?p=48"},"modified":"2023-07-30T14:08:27","modified_gmt":"2023-07-30T14:08:27","slug":"modelagem-e-costura-o-que-sao-e-como-se-complementam","status":"publish","type":"post","link":"https:\/\/www.tracosepontos.pt\/blog\/modelagem-e-costura-o-que-sao-e-como-se-complementam\/","title":{"rendered":"Modelagem e costura: o que s\u00e3o e como se complementam."},"content":{"rendered":"<div class=\"text-block-167\">A modelagem e a costura s\u00e3o etapas essenciais para a cria\u00e7\u00e3o de roupas e alguns acess\u00f3rios, elas se complementam e juntas transformam uma ideia em uma pe\u00e7a tang\u00edvel. Entender o que s\u00e3o e a sua hist\u00f3ria \u00e9 muito importante para ter um embasamento te\u00f3rico nessa pr\u00e1tica t\u00e3o conhecida. Continue lendo para saber mais.<\/div>\n<div class=\"rich-text-block-4 w-richtext\">\n<p><strong>O que \u00e9 Modelagem\u00a0<\/strong><\/p>\n<p>Modelagem envolve o desenvolvimento e cria\u00e7\u00e3o de moldes dos quais roupas e acess\u00f3rios podem ser costurados. Moldes s\u00e3o feitos de papel que s\u00e3o tra\u00e7ados no tecido para serem cortados.<br \/>\nA modelagem pode ser feita do zero por modelistas experientes ou pr\u00e9 adquiridas para projetos de modelagem.<\/p>\n<p>\u200d<\/p>\n<figure class=\"w-richtext-figure-type-image w-richtext-align-center\">\n<div><img decoding=\"async\" src=\"https:\/\/uploads-ssl.webflow.com\/5bae826a1af2ce271015dc02\/632b66aff8c4c3098219f617_Modelista.jpg\" alt=\"Modelagem envolve o desenvolvimento e cria\u00e7\u00e3o de moldes dos quais roupas e acess\u00f3rios podem ser costurados. Moldes s\u00e3o feitos de papel que s\u00e3o tra\u00e7ados no tecido para serem cortados. A modelagem pode ser feita do zero por modelistas experientes ou pr\u00e9 adquiridas para projetos de modelagem.\u00a0\" \/><\/div><figcaption>Modelista cortando molde\u00a0<\/figcaption><\/figure>\n<p>\u200d<\/p>\n<p><strong>Software de Modelagem\u00a0<\/strong><\/p>\n<p>Tamb\u00e9m existem softwares desenvolvidos tanto para uso industrial quanto caseiro, que podem ser usados para modelagem.<br \/>\nO <a href=\"https:\/\/www.molde.me\/blog\/software-cad-o-que-e-e-seu-uso-na-modelagem-textil\">software CAD<\/a> pode ser assinado e acessado pela nuvem no computador do usu\u00e1rio, com o objetivo de editar moldes antigos ou criar moldes novos.<br \/>\nEsse tipo de software permite que voc\u00ea rapidamente edite, fa\u00e7a grada\u00e7\u00e3o, mude o tamanho da pe\u00e7a e muitas outras funcionalidades que garantem um caimento perfeito na produ\u00e7\u00e3o de roupas. Ap\u00f3s ter os moldes de roupas prontos, \u00e9 s\u00f3 imprimi-los e seguir os passos convencionais citados acima.<br \/>\nPara saber mais sobre o software de modelagem digital, ferramentas para modelagem e encaixe autom\u00e1tico da Molde.me, \u00e9 s\u00f3 nos chamar no <a href=\"https:\/\/wa.link\/3ebxr2\">WhatsApp<\/a>.<\/p>\n<p>\u200d<\/p>\n<p>\u200d<\/p>\n<figure class=\"w-richtext-figure-type-image w-richtext-align-center\">\n<div><img decoding=\"async\" src=\"https:\/\/uploads-ssl.webflow.com\/5bae826a1af2ce271015dc02\/632b67dc34dcb74874b1ed16_Molde-me-122-min.JPG\" alt=\"Tamb\u00e9m existem softwares desenvolvidos tanto para uso industrial quanto caseiro, que podem ser usados para modelagem. O software CAD pode ser assinado e acessado pela nuvem no computador do usu\u00e1rio, com o objetivo de editar moldes antigos ou criar novos\" \/><\/div><figcaption>Sistema de modelagem digital e encaixe autom\u00e1tico\u00a0<\/figcaption><\/figure>\n<p>\u200d<\/p>\n<p><strong>Hist\u00f3ria da Modelagem\u00a0<\/strong><\/p>\n<p>Antes do desenvolvimento do software CAD, a modelagem j\u00e1 esteve presente por um bom tempo, por\u00e9m a confec\u00e7\u00e3o de moldes era quase exclusivamente para criar pe\u00e7as para aristocratas ou os mais ricos.<br \/>\nAntes do s\u00e9culo 19, era raro para a maioria das pessoas ter acesso \u00e0 roupas que eram adaptadas para tamanhos individuais e depois vendidas. Em 1869, Ebenezer Butterick pr\u00e9-imprimiu moldes em papel de seda que foram graduados para tamanhos individuais e depois vendidos.<br \/>\nDurante o mesmo per\u00edodo, em pa\u00edses industrializados, m\u00e1quinas de costura se tornaram mais acess\u00edveis para confec\u00e7\u00e3o de roupas.<br \/>\nEsses dois eventos deram crescimento \u00e0 ind\u00fastria da modelagem, com empresas produzindo em massa moldes para venda e pessoas tendo acesso \u00e0 m\u00e1quinas de costura podendo comprar esses moldes e us\u00e1-los em casa.<\/p>\n<p>\u200d<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>A modelagem e a costura s\u00e3o etapas essenciais para a cria\u00e7\u00e3o de roupas e alguns acess\u00f3rios, elas se complementam e juntas transformam uma ideia em uma pe\u00e7a tang\u00edvel. Entender o que s\u00e3o&#8230;<\/p>\n","protected":false},"author":1,"featured_media":30,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[4],"tags":[],"_links":{"self":[{"href":"https:\/\/www.tracosepontos.pt\/blog\/wp-json\/wp\/v2\/posts\/48"}],"collection":[{"href":"https:\/\/www.tracosepontos.pt\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tracosepontos.pt\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tracosepontos.pt\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tracosepontos.pt\/blog\/wp-json\/wp\/v2\/comments?post=48"}],"version-history":[{"count":1,"href":"https:\/\/www.tracosepontos.pt\/blog\/wp-json\/wp\/v2\/posts\/48\/revisions"}],"predecessor-version":[{"id":49,"href":"https:\/\/www.tracosepontos.pt\/blog\/wp-json\/wp\/v2\/posts\/48\/revisions\/49"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tracosepontos.pt\/blog\/wp-json\/wp\/v2\/media\/30"}],"wp:attachment":[{"href":"https:\/\/www.tracosepontos.pt\/blog\/wp-json\/wp\/v2\/media?parent=48"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tracosepontos.pt\/blog\/wp-json\/wp\/v2\/categories?post=48"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tracosepontos.pt\/blog\/wp-json\/wp\/v2\/tags?post=48"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}